{"id":2767,"date":"2024-05-02T11:20:32","date_gmt":"2024-05-02T15:20:32","guid":{"rendered":"http:\/\/vps1.facyt.uc.edu.ve\/web\/?p=2767"},"modified":"2024-05-02T11:21:47","modified_gmt":"2024-05-02T15:21:47","slug":"fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024","status":"publish","type":"post","link":"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/","title":{"rendered":"Fotograf\u00edas de participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024."},"content":{"rendered":"<p>La Coordinaci\u00f3n de cultura de Facyt se complace en compartir con ustedes las fotograf\u00edas participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024.<\/p>\n<p>Las fotograf\u00edas admitidas son aquellas que han pasado por un riguroso proceso de selecci\u00f3n, donde se ha evaluado la calidad, tem\u00e1tica y t\u00e9cnica art\u00edstica de cada una. Si tu foto ha sido seleccionada, \u00a1felicidades!<\/p>\n<p>En resumen, las fotograf\u00edas admitidas para el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024 fueron seleccionadas por profesionales en las \u00e1reas de fotograf\u00eda y Artes visuales integrado por:<\/p>\n<p>Isabel Falc\u00f3n Docente- Fot\u00f3grafa<\/p>\n<p>Victor Hern\u00e1ndez Fot\u00f3grafo- investigador<\/p>\n<p>Mar\u00eda de Lourdes Rivero M\u00e9dico &#8211; Docente Investigador<\/p>\n<p>gracias a todos los participantes:Estudiantes, Docentes y personal Administrativo de la FACYT por demostrar su creatividad en cada una de sus fotograf\u00edas.<\/p>\n<p>Para aquellos que no han sido seleccionados, no se desanimen. La fotograf\u00eda es un arte subjetivo y lo importante es seguir practicando y mejorando cada d\u00eda. Adem\u00e1s, siempre hay nuevas oportunidades para demostrar su talento.<\/p>\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-2767-1\" width=\"640\" height=\"640\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.facyt.uc.edu.ve\/web\/wp-content\/uploads\/2024\/05\/WhatsApp-Video-2024-05-02-at-10.50.54-AM.mp4?_=1\" \/><a href=\"https:\/\/www.facyt.uc.edu.ve\/web\/wp-content\/uploads\/2024\/05\/WhatsApp-Video-2024-05-02-at-10.50.54-AM.mp4\">https:\/\/www.facyt.uc.edu.ve\/web\/wp-content\/uploads\/2024\/05\/WhatsApp-Video-2024-05-02-at-10.50.54-AM.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Coordinaci\u00f3n de cultura de Facyt se complace en compartir con ustedes las fotograf\u00edas participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024. Las fotograf\u00edas admitidas son aquellas que han pasado por un riguroso proceso de selecci\u00f3n, donde se ha evaluado la calidad, tem\u00e1tica y t\u00e9cnica art\u00edstica de cada una. Si tu foto&hellip;<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-2767","post","type-post","status-publish","format-standard","hentry","category-extension"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fotograf\u00edas de participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024. - Facultad Experimental de Ciencias y Tecnolog\u00eda<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fotograf\u00edas de participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024. - Facultad Experimental de Ciencias y Tecnolog\u00eda\" \/>\n<meta property=\"og:description\" content=\"La Coordinaci\u00f3n de cultura de Facyt se complace en compartir con ustedes las fotograf\u00edas participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024. Las fotograf\u00edas admitidas son aquellas que han pasado por un riguroso proceso de selecci\u00f3n, donde se ha evaluado la calidad, tem\u00e1tica y t\u00e9cnica art\u00edstica de cada una. Si tu foto&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Facultad Experimental de Ciencias y Tecnolog\u00eda\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T15:20:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-02T15:21:47+00:00\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo estimado de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/#\/schema\/person\/bf524fd52b6d2f467be80da039251a72\"},\"headline\":\"Fotograf\u00edas de participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024.\",\"datePublished\":\"2024-05-02T15:20:32+00:00\",\"dateModified\":\"2024-05-02T15:21:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/\"},\"wordCount\":218,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/#organization\"},\"articleSection\":[\"Extension\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/\",\"url\":\"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/\",\"name\":\"Fotograf\u00edas de participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024. - Facultad Experimental de Ciencias y Tecnolog\u00eda\",\"isPartOf\":{\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/#website\"},\"datePublished\":\"2024-05-02T15:20:32+00:00\",\"dateModified\":\"2024-05-02T15:21:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.facyt.uc.edu.ve\/web\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fotograf\u00edas de participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/#website\",\"url\":\"https:\/\/www.facyt.uc.edu.ve\/web\/\",\"name\":\"Facultad Experimental de Ciencias y Tecnolog\u00eda\",\"description\":\"FaCyT UC\",\"publisher\":{\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/#organization\"},\"alternateName\":\"FaCyT\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.facyt.uc.edu.ve\/web\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/#organization\",\"name\":\"Facultad Experimental de Ciencias y Tecnolog\u00eda\",\"url\":\"https:\/\/www.facyt.uc.edu.ve\/web\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.facyt.uc.edu.ve\/web\/wp-content\/uploads\/2025\/11\/Logo_de_la_Facultad_Experimental_de_Ciencia_y_Tecnologia-scaled.jpg\",\"contentUrl\":\"https:\/\/www.facyt.uc.edu.ve\/web\/wp-content\/uploads\/2025\/11\/Logo_de_la_Facultad_Experimental_de_Ciencia_y_Tecnologia-scaled.jpg\",\"width\":2560,\"height\":2560,\"caption\":\"Facultad Experimental de Ciencias y Tecnolog\u00eda\"},\"image\":{\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/instagram.com\/facytuc.oficial\/yoast\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/#\/schema\/person\/bf524fd52b6d2f467be80da039251a72\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.facyt.uc.edu.ve\/web\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2c3e463b47acb8ec913b8eadbcb6618ae1986ac22dca6b407c47e7229e4bef8f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2c3e463b47acb8ec913b8eadbcb6618ae1986ac22dca6b407c47e7229e4bef8f?s=96&d=mm&r=g\",\"caption\":\"Admin\"},\"url\":\"https:\/\/www.facyt.uc.edu.ve\/web\/author\/imoreno\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fotograf\u00edas de participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024. - Facultad Experimental de Ciencias y Tecnolog\u00eda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/","og_locale":"es_ES","og_type":"article","og_title":"Fotograf\u00edas de participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024. - Facultad Experimental de Ciencias y Tecnolog\u00eda","og_description":"La Coordinaci\u00f3n de cultura de Facyt se complace en compartir con ustedes las fotograf\u00edas participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024. Las fotograf\u00edas admitidas son aquellas que han pasado por un riguroso proceso de selecci\u00f3n, donde se ha evaluado la calidad, tem\u00e1tica y t\u00e9cnica art\u00edstica de cada una. Si tu foto&hellip;","og_url":"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/","og_site_name":"Facultad Experimental de Ciencias y Tecnolog\u00eda","article_published_time":"2024-05-02T15:20:32+00:00","article_modified_time":"2024-05-02T15:21:47+00:00","author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Admin","Tiempo estimado de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/#article","isPartOf":{"@id":"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/"},"author":{"name":"Admin","@id":"https:\/\/www.facyt.uc.edu.ve\/web\/#\/schema\/person\/bf524fd52b6d2f467be80da039251a72"},"headline":"Fotograf\u00edas de participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024.","datePublished":"2024-05-02T15:20:32+00:00","dateModified":"2024-05-02T15:21:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/"},"wordCount":218,"commentCount":0,"publisher":{"@id":"https:\/\/www.facyt.uc.edu.ve\/web\/#organization"},"articleSection":["Extension"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/","url":"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/","name":"Fotograf\u00edas de participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024. - Facultad Experimental de Ciencias y Tecnolog\u00eda","isPartOf":{"@id":"https:\/\/www.facyt.uc.edu.ve\/web\/#website"},"datePublished":"2024-05-02T15:20:32+00:00","dateModified":"2024-05-02T15:21:47+00:00","breadcrumb":{"@id":"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.facyt.uc.edu.ve\/web\/fotografias-participantes-en-el-segundo-salon-virtual-sectorial-de-fotografia-facyt-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.facyt.uc.edu.ve\/web\/"},{"@type":"ListItem","position":2,"name":"Fotograf\u00edas de participantes en el segundo sal\u00f3n Virtual Sectorial de fotograf\u00eda FACYT 2024."}]},{"@type":"WebSite","@id":"https:\/\/www.facyt.uc.edu.ve\/web\/#website","url":"https:\/\/www.facyt.uc.edu.ve\/web\/","name":"Facultad Experimental de Ciencias y Tecnolog\u00eda","description":"FaCyT UC","publisher":{"@id":"https:\/\/www.facyt.uc.edu.ve\/web\/#organization"},"alternateName":"FaCyT","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.facyt.uc.edu.ve\/web\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.facyt.uc.edu.ve\/web\/#organization","name":"Facultad Experimental de Ciencias y Tecnolog\u00eda","url":"https:\/\/www.facyt.uc.edu.ve\/web\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.facyt.uc.edu.ve\/web\/#\/schema\/logo\/image\/","url":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-content\/uploads\/2025\/11\/Logo_de_la_Facultad_Experimental_de_Ciencia_y_Tecnologia-scaled.jpg","contentUrl":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-content\/uploads\/2025\/11\/Logo_de_la_Facultad_Experimental_de_Ciencia_y_Tecnologia-scaled.jpg","width":2560,"height":2560,"caption":"Facultad Experimental de Ciencias y Tecnolog\u00eda"},"image":{"@id":"https:\/\/www.facyt.uc.edu.ve\/web\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/instagram.com\/facytuc.oficial\/yoast"]},{"@type":"Person","@id":"https:\/\/www.facyt.uc.edu.ve\/web\/#\/schema\/person\/bf524fd52b6d2f467be80da039251a72","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.facyt.uc.edu.ve\/web\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/2c3e463b47acb8ec913b8eadbcb6618ae1986ac22dca6b407c47e7229e4bef8f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2c3e463b47acb8ec913b8eadbcb6618ae1986ac22dca6b407c47e7229e4bef8f?s=96&d=mm&r=g","caption":"Admin"},"url":"https:\/\/www.facyt.uc.edu.ve\/web\/author\/imoreno\/"}]}},"_links":{"self":[{"href":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-json\/wp\/v2\/posts\/2767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-json\/wp\/v2\/comments?post=2767"}],"version-history":[{"count":2,"href":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-json\/wp\/v2\/posts\/2767\/revisions"}],"predecessor-version":[{"id":2770,"href":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-json\/wp\/v2\/posts\/2767\/revisions\/2770"}],"wp:attachment":[{"href":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-json\/wp\/v2\/media?parent=2767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-json\/wp\/v2\/categories?post=2767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.facyt.uc.edu.ve\/web\/wp-json\/wp\/v2\/tags?post=2767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}